{"id":4324,"date":"2023-09-24T21:45:04","date_gmt":"2023-09-24T19:45:04","guid":{"rendered":"https:\/\/www.fondazionearnaldopomodoro.it\/?p=4324"},"modified":"2024-02-26T14:57:15","modified_gmt":"2024-02-26T13:57:15","slug":"loris-cecchini-vague-rules-for-a-growing-plant-2013","status":"publish","type":"post","link":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/","title":{"rendered":"Cecchini Loris, <em>Vague Rules for a growing plant<\/em> (2013)"},"content":{"rendered":"\r\n\t\t<div id=\"fws_6a04b644369ac\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  right_padding_10pct left_padding_10pct\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation padding-2-percent inherit_tablet inherit_phone \"  data-padding-pos=\"bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"904\" width=\"900\" data-animation=\"none\" src=\"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg\" alt=\"\" srcset=\"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg 900w, https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio-768x771.jpg 768w, https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio-12x12.jpg 12w, https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio-140x140.jpg 140w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-1-percent inherit_tablet inherit_phone \"  data-padding-pos=\"left\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element \" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4><strong>Loris Cecchini<\/strong><em><strong><br \/>\n<\/strong>Vague Rules for a growing plant<\/em>, 2013<\/h4>\n<p>tecnica mista, 60 \u00d7 60 \u00d7 8 cm<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element \" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Donata alla Fondazione dall\u2019artista, vincitore della terza edizione del <a href=\"https:\/\/www.fondazionearnaldopomodoro.it\/la-fondazione\/premio-arnaldo-pomodoro-per-la-scultura\/\"><em>Premio Arnaldo Pomodoro<\/em> <em>per la Scultura<\/em><\/a> (2014), quest\u2019opera di Loris Cecchini \u00e8 rappresentativa del suo interesse per la \u201cmodellizzazione\u201d, intesa come &#8220;processo cognitivo volto alla creazione schematica di un piccolo universo semantico atto alla definizione di un evento, [che] non \u00e8 in s\u00e9 un processo estetico, e non rientra solitamente negli interessi del linguaggio dell\u2019arte quanto rientra invece in tutte quelle discipline \u2013 dalla fisica all\u2019economia \u2013 che necessitano di uniformare i fenomeni, ma il fascino suscitato dalla possibilit\u00e0, o anche solo dal sistema logico entro cui inserire qualsiasi oggetto o avvenimento, o combinazione di oggetti con avvenimenti, \u00e8 tale che il tentativo di trasferire un modulo spaziale in un sistema pi\u00f9 complesso \u00e8 una sfida che l\u2019artista accetta e cerca, con una consapevolezza chiara e sinora inedita&#8221;.<\/p>\n<p>da: <a href=\"https:\/\/shop.fondazionearnaldopomodoro.it\/it\/libri-su-artisti-vari\/22445-loris-cecchini-modulo-e-modello\"><em>Loris Cecchini. Modulo e modello<\/em><\/a>, catalogo della mostra, a cura di M. Meneguzzo, Milano, Fondazione Arnaldo Pomodoro, 2014, pp. 17-18.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Loris Cecchini Vague Rules for a growing plant, 2013 tecnica mista, 60 \u00d7 60 \u00d7 8 cm Donata alla Fondazione dall\u2019artista, vincitore della terza edizione del Premio Arnaldo Pomodoro per...","protected":false},"author":1,"featured_media":5792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,20],"tags":[],"class_list":{"0":"post-4324","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-altri-artisti","8":"category-le-opere-della-collezione"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cecchini Loris, Vague Rules for a growing plant (2013) - Fondazione Arnaldo Pomodoro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionearnaldopomodoro.it\/en\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cecchini Loris, Vague Rules for a growing plant (2013) - Fondazione Arnaldo Pomodoro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionearnaldopomodoro.it\/en\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Arnaldo Pomodoro\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-24T19:45:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-26T13:57:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"904\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nowheredemo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nowheredemo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/\"},\"author\":{\"name\":\"nowheredemo\",\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/#\\\/schema\\\/person\\\/6fe3d3f6a2a33a0f99147fb520d865c2\"},\"headline\":\"Cecchini Loris, Vague Rules for a growing plant (2013)\",\"datePublished\":\"2023-09-24T19:45:04+00:00\",\"dateModified\":\"2024-02-26T13:57:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/\"},\"wordCount\":506,\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Loris-Ceccini-Vague-Rules-dettaglio.jpg\",\"articleSection\":[\"Altri artisti\",\"Tutte le opere\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/\",\"url\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/\",\"name\":\"Cecchini Loris, Vague Rules for a growing plant (2013) - Fondazione Arnaldo Pomodoro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Loris-Ceccini-Vague-Rules-dettaglio.jpg\",\"datePublished\":\"2023-09-24T19:45:04+00:00\",\"dateModified\":\"2024-02-26T13:57:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/#\\\/schema\\\/person\\\/6fe3d3f6a2a33a0f99147fb520d865c2\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/loris-cecchini-vague-rules-for-a-growing-plant-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Loris-Ceccini-Vague-Rules-dettaglio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Loris-Ceccini-Vague-Rules-dettaglio.jpg\",\"width\":900,\"height\":904},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/#website\",\"url\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/\",\"name\":\"Fondazione Arnaldo Pomodoro\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/#\\\/schema\\\/person\\\/6fe3d3f6a2a33a0f99147fb520d865c2\",\"name\":\"nowheredemo\",\"sameAs\":[\"http:\\\/\\\/www.fondazionearnaldopomodoro.it\"],\"url\":\"https:\\\/\\\/www.fondazionearnaldopomodoro.it\\\/en\\\/author\\\/nowheredemo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cecchini Loris, Vague Rules for a growing plant (2013) - Fondazione Arnaldo Pomodoro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/","og_locale":"en_GB","og_type":"article","og_title":"Cecchini Loris, Vague Rules for a growing plant (2013) - Fondazione Arnaldo Pomodoro","og_url":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/","og_site_name":"Fondazione Arnaldo Pomodoro","article_published_time":"2023-09-24T19:45:04+00:00","article_modified_time":"2024-02-26T13:57:15+00:00","og_image":[{"width":900,"height":904,"url":"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg","type":"image\/jpeg"}],"author":"nowheredemo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nowheredemo","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/#article","isPartOf":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/"},"author":{"name":"nowheredemo","@id":"https:\/\/www.fondazionearnaldopomodoro.it\/#\/schema\/person\/6fe3d3f6a2a33a0f99147fb520d865c2"},"headline":"Cecchini Loris, Vague Rules for a growing plant (2013)","datePublished":"2023-09-24T19:45:04+00:00","dateModified":"2024-02-26T13:57:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/"},"wordCount":506,"image":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg","articleSection":["Altri artisti","Tutte le opere"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/","url":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/","name":"Cecchini Loris, Vague Rules for a growing plant (2013) - Fondazione Arnaldo Pomodoro","isPartOf":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg","datePublished":"2023-09-24T19:45:04+00:00","dateModified":"2024-02-26T13:57:15+00:00","author":{"@id":"https:\/\/www.fondazionearnaldopomodoro.it\/#\/schema\/person\/6fe3d3f6a2a33a0f99147fb520d865c2"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.fondazionearnaldopomodoro.it\/loris-cecchini-vague-rules-for-a-growing-plant-2013\/#primaryimage","url":"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg","contentUrl":"https:\/\/www.fondazionearnaldopomodoro.it\/wp-content\/uploads\/2023\/09\/Loris-Ceccini-Vague-Rules-dettaglio.jpg","width":900,"height":904},{"@type":"WebSite","@id":"https:\/\/www.fondazionearnaldopomodoro.it\/#website","url":"https:\/\/www.fondazionearnaldopomodoro.it\/","name":"Fondazione Arnaldo Pomodoro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionearnaldopomodoro.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.fondazionearnaldopomodoro.it\/#\/schema\/person\/6fe3d3f6a2a33a0f99147fb520d865c2","name":"nowheredemo","sameAs":["http:\/\/www.fondazionearnaldopomodoro.it"],"url":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/author\/nowheredemo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/posts\/4324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/comments?post=4324"}],"version-history":[{"count":7,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/posts\/4324\/revisions"}],"predecessor-version":[{"id":7009,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/posts\/4324\/revisions\/7009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/media\/5792"}],"wp:attachment":[{"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/media?parent=4324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/categories?post=4324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionearnaldopomodoro.it\/en\/wp-json\/wp\/v2\/tags?post=4324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}